{"id":159837,"date":"2020-08-03T00:00:00","date_gmt":"2020-08-02T21:00:00","guid":{"rendered":"http:\/\/south.euneighbours.eu\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies-renouvelables-et-de-lefficacite-energetique\/"},"modified":"2022-07-12T11:38:00","modified_gmt":"2022-07-12T08:38:00","slug":"maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies","status":"publish","type":"news","link":"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/","title":{"rendered":"Maroc : Cr\u00e9ation de trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique"},"content":{"rendered":"<p>Avec le soutien financier de l\u2019Union europ\u00e9enne, le Maroc a cr\u00e9\u00e9 trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (IFMEREE) \u00e0 Oujda, Tanger et Ouarzazate. Destin\u00e9s \u00e0 accompagner la strat\u00e9gie \u00e9nerg\u00e9tique nationale du Royaume, ces instituts offrent des cursus dans le domaine de la formation aux m\u00e9tiers verts pour r\u00e9pondre aux besoins d\u2019un march\u00e9 des \u00e9nergies renouvelables en tr\u00e8s forte croissance.<\/p>\n<p>Visant \u00e0 devenir un des leaders mondiaux de la transition vers des \u00e9nergies propres, le Maroc encourage les investissements dans le solaire et l\u2019\u00e9olien. Avec l\u2019accompagnement de l\u2019Union europ\u00e9enne, la strat\u00e9gie \u00e9nerg\u00e9tique du pays vise \u00e0 porter la part des \u00e9nergies renouvelables dans la production \u00e9lectrique \u00e0 52% d\u2019ici \u00e0 2030 ce qui permettrait la cr\u00e9ation de plus de 50\u00a0000 nouveaux emplois dans ce secteur.\u00a0<\/p>\n<p>Ouvert en 2015, l\u2019IFMEREE \u00e0 Oujdaa a d\u00e9j\u00e0 accueilli plusieurs promotions en respectant la parit\u00e9 femmes-hommes. A Ouarzazate, la premi\u00e8re promotion commencera la formation \u00e0 la rentr\u00e9e 2020-2021 alors qu\u2019\u00e0 Tanger, la premi\u00e8re promotion a \u00e9t\u00e9 accueillie depuis septembre 2019. Les IFMEREE auront pour objectif de former mille personnes par an.<\/p>\n<p>Des sessions de formation continue seront aussi propos\u00e9es aux employ\u00e9s des entreprises du secteur des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tiques dans les trois villes concern\u00e9es. Gr\u00e2ce \u00e0 leurs ateliers de derni\u00e8re g\u00e9n\u00e9ration et \u00e0 leur infrastructure de pointe, les IFMEREE suivent de pr\u00e8s l\u2019\u00e9volution constante du march\u00e9 des \u00e9nergies renouvelables.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Pour en savoir plus<\/strong><\/p>\n<p><a href=\"https:\/\/www.majalat.org\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies-renouvelables-et-de\">Communiqu\u00e9 de presse<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"featured_media":57843,"parent":0,"template":"","news_category":[],"country":[1953],"special_action":[],"custom_tag":[1884],"class_list":["post-159837","news","type-news","status-publish","has-post-thumbnail","hentry","country-maroc","custom_tag-environnement-et-changement-climatique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maroc : Cr\u00e9ation de trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique - Voisins de l&#039;UE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maroc : Cr\u00e9ation de trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique - Voisins de l&#039;UE\" \/>\n<meta property=\"og:description\" content=\"Avec le soutien financier de l\u2019Union europ\u00e9enne, le Maroc a cr\u00e9\u00e9 trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (IFMEREE) \u00e0 Oujda, Tanger et Ouarzazate. Destin\u00e9s \u00e0 accompagner la strat\u00e9gie \u00e9nerg\u00e9tique nationale du Royaume, ces instituts offrent des cursus dans le domaine de la formation aux m\u00e9tiers verts pour r\u00e9pondre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/\" \/>\n<meta property=\"og:site_name\" content=\"Voisins de l&#039;UE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eumedbridge\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-12T08:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/photo-maroc_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eumedbridge\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/\",\"url\":\"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/\",\"name\":\"Maroc : Cr\u00e9ation de trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique - Voisins de l'UE\",\"isPartOf\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/photo-maroc_0.jpg\",\"datePublished\":\"2020-08-02T21:00:00+00:00\",\"dateModified\":\"2022-07-12T08:38:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/#primaryimage\",\"url\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/photo-maroc_0.jpg\",\"contentUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/photo-maroc_0.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eumedbridge.eu\/fr\/home-page\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\",\"item\":\"https:\/\/www.eumedbridge.eu\/fr\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maroc : Cr\u00e9ation de trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#website\",\"url\":\"https:\/\/www.eumedbridge.eu\/\",\"name\":\"EU Medbridge\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eumedbridge.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#organization\",\"name\":\"EU Medbridge\",\"url\":\"https:\/\/www.eumedbridge.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png\",\"contentUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png\",\"width\":325,\"height\":114,\"caption\":\"EU Medbridge\"},\"image\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eumedbridge\/\",\"https:\/\/x.com\/eumedbridge\",\"https:\/\/www.linkedin.com\/company\/eumedbridge\",\"https:\/\/www.youtube.com\/@eumedbridge\",\"https:\/\/www.instagram.com\/eumedbridge\",\"https:\/\/www.flickr.com\/photos\/euneighbours-south\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maroc : Cr\u00e9ation de trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique - Voisins de l'UE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/","og_locale":"fr_FR","og_type":"article","og_title":"Maroc : Cr\u00e9ation de trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique - Voisins de l'UE","og_description":"Avec le soutien financier de l\u2019Union europ\u00e9enne, le Maroc a cr\u00e9\u00e9 trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (IFMEREE) \u00e0 Oujda, Tanger et Ouarzazate. Destin\u00e9s \u00e0 accompagner la strat\u00e9gie \u00e9nerg\u00e9tique nationale du Royaume, ces instituts offrent des cursus dans le domaine de la formation aux m\u00e9tiers verts pour r\u00e9pondre [&hellip;]","og_url":"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/","og_site_name":"Voisins de l'UE","article_publisher":"https:\/\/www.facebook.com\/eumedbridge\/","article_modified_time":"2022-07-12T08:38:00+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/photo-maroc_0.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@eumedbridge","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/","url":"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/","name":"Maroc : Cr\u00e9ation de trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique - Voisins de l'UE","isPartOf":{"@id":"https:\/\/www.eumedbridge.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/#primaryimage"},"image":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/photo-maroc_0.jpg","datePublished":"2020-08-02T21:00:00+00:00","dateModified":"2022-07-12T08:38:00+00:00","breadcrumb":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/#primaryimage","url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/photo-maroc_0.jpg","contentUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/photo-maroc_0.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.eumedbridge.eu\/fr\/news\/maroc-creation-de-trois-instituts-de-formation-aux-metiers-des-energies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eumedbridge.eu\/fr\/home-page\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s","item":"https:\/\/www.eumedbridge.eu\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Maroc : Cr\u00e9ation de trois Instituts de formation aux m\u00e9tiers des \u00e9nergies renouvelables et de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique"}]},{"@type":"WebSite","@id":"https:\/\/www.eumedbridge.eu\/#website","url":"https:\/\/www.eumedbridge.eu\/","name":"EU Medbridge","description":"","publisher":{"@id":"https:\/\/www.eumedbridge.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eumedbridge.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eumedbridge.eu\/#organization","name":"EU Medbridge","url":"https:\/\/www.eumedbridge.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png","contentUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png","width":325,"height":114,"caption":"EU Medbridge"},"image":{"@id":"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eumedbridge\/","https:\/\/x.com\/eumedbridge","https:\/\/www.linkedin.com\/company\/eumedbridge","https:\/\/www.youtube.com\/@eumedbridge","https:\/\/www.instagram.com\/eumedbridge","https:\/\/www.flickr.com\/photos\/euneighbours-south\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/news\/159837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/media\/57843"}],"wp:attachment":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/media?parent=159837"}],"wp:term":[{"taxonomy":"news_category","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/news_category?post=159837"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/country?post=159837"},{"taxonomy":"special_action","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/special_action?post=159837"},{"taxonomy":"custom_tag","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/custom_tag?post=159837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}