{"id":173379,"date":"2020-01-30T00:00:00","date_gmt":"2020-01-29T22:00:00","guid":{"rendered":"http:\/\/south.euneighbours.eu\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/"},"modified":"2022-07-08T14:18:56","modified_gmt":"2022-07-08T11:18:56","slug":"guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques","status":"publish","type":"publication","link":"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/","title":{"rendered":"Guide meetMED de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques"},"content":{"rendered":"<p><span><span><span><span>Cette publication meetMED contient les informations n\u00e9cessaires pour une formation professionnelle, qui vise \u00e0 renforcer la capacit\u00e9 technique des autorit\u00e9s locales et nationales pour concevoir, financer et mettre en \u0153uvre les solutions d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (EE) et d\u2019\u00e9nergie renouvelable (ER). <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>Cette publication est le guide de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques, qui peut \u00eatre reproduit au profit de tous les pays de la r\u00e9gion m\u00e9diterran\u00e9enne. <\/span><\/span><\/span><\/span><\/p>\n<p><span><span><span><span>Le pack inclut des modules sur une multitude de sujets\u00a0: la politique \u00e9nerg\u00e9tique en g\u00e9n\u00e9ral, le r\u00f4le des autorit\u00e9s publiques menant \u00e0 l\u2019adoption de mesures li\u00e9es \u00e0 l\u2019EE et \u00e0 l\u2019ER, la planification \u00e9nerg\u00e9tique, le r\u00f4le des gestionnaires de l\u2019\u00e9nergie, les instruments financiers, le r\u00f4le des communaut\u00e9s \u00e9nerg\u00e9tiques et la Convention des Maires, les villes intelligentes et les secteurs \u00e0 forte intensit\u00e9 \u00e9nerg\u00e9tique comme l\u2019\u00e9clairage, l\u2019eau et les b\u00e2timents publics.<\/span><\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":127587,"parent":0,"template":"","publication_category":[],"country":[1946,1947,1950,2124,1949,1951,1953,1952,1955],"special_action":[],"custom_tag":[1884],"class_list":["post-173379","publication","type-publication","status-publish","has-post-thumbnail","hentry","country-algerie","country-egypte","country-israel-fr","country-jordanie","country-liban","country-libye","country-maroc","country-palestine-fr","country-tunisie","custom_tag-environnement-et-changement-climatique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guide meetMED de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques - Voisins de l&#039;UE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guide meetMED de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques - Voisins de l&#039;UE\" \/>\n<meta property=\"og:description\" content=\"Cette publication meetMED contient les informations n\u00e9cessaires pour une formation professionnelle, qui vise \u00e0 renforcer la capacit\u00e9 technique des autorit\u00e9s locales et nationales pour concevoir, financer et mettre en \u0153uvre les solutions d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (EE) et d\u2019\u00e9nergie renouvelable (ER). Cette publication est le guide de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques, qui peut \u00eatre reproduit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Voisins de l&#039;UE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eumedbridge\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T11:18:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/Capture_12-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"514\" \/>\n\t<meta property=\"og:image:height\" content=\"729\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eumedbridge\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/\",\"url\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/\",\"name\":\"Guide meetMED de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques - Voisins de l'UE\",\"isPartOf\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/Capture_12-10.jpg\",\"datePublished\":\"2020-01-29T22:00:00+00:00\",\"dateModified\":\"2022-07-08T11:18:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/#primaryimage\",\"url\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/Capture_12-10.jpg\",\"contentUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/Capture_12-10.jpg\",\"width\":514,\"height\":729},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eumedbridge.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publications\",\"item\":\"https:\/\/www.eumedbridge.eu\/publication\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guide meetMED de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#website\",\"url\":\"https:\/\/www.eumedbridge.eu\/\",\"name\":\"EU Medbridge\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eumedbridge.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#organization\",\"name\":\"EU Medbridge\",\"url\":\"https:\/\/www.eumedbridge.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png\",\"contentUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png\",\"width\":325,\"height\":114,\"caption\":\"EU Medbridge\"},\"image\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eumedbridge\/\",\"https:\/\/x.com\/eumedbridge\",\"https:\/\/www.linkedin.com\/company\/eumedbridge\",\"https:\/\/www.youtube.com\/@eumedbridge\",\"https:\/\/www.instagram.com\/eumedbridge\",\"https:\/\/www.flickr.com\/photos\/euneighbours-south\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guide meetMED de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques - Voisins de l'UE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Guide meetMED de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques - Voisins de l'UE","og_description":"Cette publication meetMED contient les informations n\u00e9cessaires pour une formation professionnelle, qui vise \u00e0 renforcer la capacit\u00e9 technique des autorit\u00e9s locales et nationales pour concevoir, financer et mettre en \u0153uvre les solutions d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (EE) et d\u2019\u00e9nergie renouvelable (ER). Cette publication est le guide de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques, qui peut \u00eatre reproduit [&hellip;]","og_url":"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/","og_site_name":"Voisins de l'UE","article_publisher":"https:\/\/www.facebook.com\/eumedbridge\/","article_modified_time":"2022-07-08T11:18:56+00:00","og_image":[{"width":514,"height":729,"url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/Capture_12-10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@eumedbridge","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/","url":"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/","name":"Guide meetMED de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques - Voisins de l'UE","isPartOf":{"@id":"https:\/\/www.eumedbridge.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/#primaryimage"},"image":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/Capture_12-10.jpg","datePublished":"2020-01-29T22:00:00+00:00","dateModified":"2022-07-08T11:18:56+00:00","breadcrumb":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/#primaryimage","url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/Capture_12-10.jpg","contentUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2022\/03\/Capture_12-10.jpg","width":514,"height":729},{"@type":"BreadcrumbList","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/guide-meetmed-de-lenergie-durable-pour-les-autorites-publiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eumedbridge.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Publications","item":"https:\/\/www.eumedbridge.eu\/publication\/"},{"@type":"ListItem","position":3,"name":"Guide meetMED de l\u2019\u00e9nergie durable pour les autorit\u00e9s publiques"}]},{"@type":"WebSite","@id":"https:\/\/www.eumedbridge.eu\/#website","url":"https:\/\/www.eumedbridge.eu\/","name":"EU Medbridge","description":"","publisher":{"@id":"https:\/\/www.eumedbridge.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eumedbridge.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eumedbridge.eu\/#organization","name":"EU Medbridge","url":"https:\/\/www.eumedbridge.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png","contentUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png","width":325,"height":114,"caption":"EU Medbridge"},"image":{"@id":"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eumedbridge\/","https:\/\/x.com\/eumedbridge","https:\/\/www.linkedin.com\/company\/eumedbridge","https:\/\/www.youtube.com\/@eumedbridge","https:\/\/www.instagram.com\/eumedbridge","https:\/\/www.flickr.com\/photos\/euneighbours-south\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication\/173379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication"}],"about":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/types\/publication"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/media\/127587"}],"wp:attachment":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/media?parent=173379"}],"wp:term":[{"taxonomy":"publication_category","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication_category?post=173379"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/country?post=173379"},{"taxonomy":"special_action","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/special_action?post=173379"},{"taxonomy":"custom_tag","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/custom_tag?post=173379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}