{"id":212711,"date":"2023-02-13T20:08:39","date_gmt":"2023-02-13T18:08:39","guid":{"rendered":"https:\/\/eumedbridge.eu\/?post_type=publication&#038;p=212711"},"modified":"2023-02-13T20:08:39","modified_gmt":"2023-02-13T18:08:39","slug":"vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter","status":"publish","type":"publication","link":"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/","title":{"rendered":"Vers le d\u00e9veloppement d\u2019une plate-forme de connaissances sur l\u2019eau concernant la r\u00e9gion SEMED \u2013 Perspectives de d\u00e9veloppement du secteur de l\u2019eau dans la r\u00e9gion m\u00e9diterran\u00e9enne"},"content":{"rendered":"<p>Situ\u00e9e au carrefour de trois continents, la r\u00e9gion m\u00e9diterran\u00e9enne est l\u2019une des plus riches sur les plans historique et culturel et l\u2019une des plus diversifi\u00e9es. En raison de ses caract\u00e9ristiques g\u00e9ographiques, \u00e9cologiques et g\u00e9opolitiques uniques, elle b\u00e9n\u00e9ficie des \u00e9changes continus entre les peuples et les territoires. Dans un monde en constante \u00e9volution, la r\u00e9gion m\u00e9diterran\u00e9enne fait face \u00e0 des d\u00e9fis importants pos\u00e9s par la nature et d\u2019origine humaine, notamment la p\u00e9nurie d\u2019eau, la croissance d\u00e9mographique, les migrations, l\u2019industrialisation, l\u2019urbanisation, la pollution, le changement climatique et autres changements environnementaux, ainsi que la multiplication des modes de vie \u00e9nergivores. Ces difficult\u00e9s donnent une image assez floue du pr\u00e9sent et de l\u2019avenir de la r\u00e9gion m\u00e9diterran\u00e9enne et menacent sa s\u00e9curit\u00e9 hydrique.<\/p>\n","protected":false},"featured_media":212607,"parent":0,"template":"","publication_category":[],"country":[1956],"special_action":[],"custom_tag":[1884],"class_list":["post-212711","publication","type-publication","status-publish","has-post-thumbnail","hentry","country-region-sud","custom_tag-environnement-et-changement-climatique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vers le d\u00e9veloppement d\u2019une plate-forme de connaissances sur l\u2019eau concernant la r\u00e9gion SEMED \u2013 Perspectives de d\u00e9veloppement du secteur de l\u2019eau dans la r\u00e9gion m\u00e9diterran\u00e9enne - Voisins de l&#039;UE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vers le d\u00e9veloppement d\u2019une plate-forme de connaissances sur l\u2019eau concernant la r\u00e9gion SEMED \u2013 Perspectives de d\u00e9veloppement du secteur de l\u2019eau dans la r\u00e9gion m\u00e9diterran\u00e9enne - Voisins de l&#039;UE\" \/>\n<meta property=\"og:description\" content=\"Situ\u00e9e au carrefour de trois continents, la r\u00e9gion m\u00e9diterran\u00e9enne est l\u2019une des plus riches sur les plans historique et culturel et l\u2019une des plus diversifi\u00e9es. En raison de ses caract\u00e9ristiques g\u00e9ographiques, \u00e9cologiques et g\u00e9opolitiques uniques, elle b\u00e9n\u00e9ficie des \u00e9changes continus entre les peuples et les territoires. Dans un monde en constante \u00e9volution, la r\u00e9gion m\u00e9diterran\u00e9enne [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/\" \/>\n<meta property=\"og:site_name\" content=\"Voisins de l&#039;UE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eumedbridge\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/02\/semed.png\" \/>\n\t<meta property=\"og:image:width\" content=\"485\" \/>\n\t<meta property=\"og:image:height\" content=\"698\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eumedbridge\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/\",\"url\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/\",\"name\":\"Vers le d\u00e9veloppement d\u2019une plate-forme de connaissances sur l\u2019eau concernant la r\u00e9gion SEMED \u2013 Perspectives de d\u00e9veloppement du secteur de l\u2019eau dans la r\u00e9gion m\u00e9diterran\u00e9enne - Voisins de l'UE\",\"isPartOf\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/02\/semed.png\",\"datePublished\":\"2023-02-13T18:08:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/#primaryimage\",\"url\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/02\/semed.png\",\"contentUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/02\/semed.png\",\"width\":485,\"height\":698},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eumedbridge.eu\/fr\/home-page\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publications\",\"item\":\"https:\/\/www.eumedbridge.eu\/publication\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vers le d\u00e9veloppement d\u2019une plate-forme de connaissances sur l\u2019eau concernant la r\u00e9gion SEMED \u2013 Perspectives de d\u00e9veloppement du secteur de l\u2019eau dans la r\u00e9gion m\u00e9diterran\u00e9enne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#website\",\"url\":\"https:\/\/www.eumedbridge.eu\/\",\"name\":\"EU Medbridge\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eumedbridge.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#organization\",\"name\":\"EU Medbridge\",\"url\":\"https:\/\/www.eumedbridge.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png\",\"contentUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png\",\"width\":325,\"height\":114,\"caption\":\"EU Medbridge\"},\"image\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eumedbridge\/\",\"https:\/\/x.com\/eumedbridge\",\"https:\/\/www.linkedin.com\/company\/eumedbridge\",\"https:\/\/www.youtube.com\/@eumedbridge\",\"https:\/\/www.instagram.com\/eumedbridge\",\"https:\/\/www.flickr.com\/photos\/euneighbours-south\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vers le d\u00e9veloppement d\u2019une plate-forme de connaissances sur l\u2019eau concernant la r\u00e9gion SEMED \u2013 Perspectives de d\u00e9veloppement du secteur de l\u2019eau dans la r\u00e9gion m\u00e9diterran\u00e9enne - Voisins de l'UE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/","og_locale":"fr_FR","og_type":"article","og_title":"Vers le d\u00e9veloppement d\u2019une plate-forme de connaissances sur l\u2019eau concernant la r\u00e9gion SEMED \u2013 Perspectives de d\u00e9veloppement du secteur de l\u2019eau dans la r\u00e9gion m\u00e9diterran\u00e9enne - Voisins de l'UE","og_description":"Situ\u00e9e au carrefour de trois continents, la r\u00e9gion m\u00e9diterran\u00e9enne est l\u2019une des plus riches sur les plans historique et culturel et l\u2019une des plus diversifi\u00e9es. En raison de ses caract\u00e9ristiques g\u00e9ographiques, \u00e9cologiques et g\u00e9opolitiques uniques, elle b\u00e9n\u00e9ficie des \u00e9changes continus entre les peuples et les territoires. Dans un monde en constante \u00e9volution, la r\u00e9gion m\u00e9diterran\u00e9enne [&hellip;]","og_url":"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/","og_site_name":"Voisins de l'UE","article_publisher":"https:\/\/www.facebook.com\/eumedbridge\/","og_image":[{"width":485,"height":698,"url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/02\/semed.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@eumedbridge","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/","url":"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/","name":"Vers le d\u00e9veloppement d\u2019une plate-forme de connaissances sur l\u2019eau concernant la r\u00e9gion SEMED \u2013 Perspectives de d\u00e9veloppement du secteur de l\u2019eau dans la r\u00e9gion m\u00e9diterran\u00e9enne - Voisins de l'UE","isPartOf":{"@id":"https:\/\/www.eumedbridge.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/#primaryimage"},"image":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/02\/semed.png","datePublished":"2023-02-13T18:08:39+00:00","breadcrumb":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/#primaryimage","url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/02\/semed.png","contentUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/02\/semed.png","width":485,"height":698},{"@type":"BreadcrumbList","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/vers-le-developpement-dune-plate-forme-de-connaissances-sur-leau-concernant-la-region-semed-perspectives-de-developpement-du-secteur-de-leau-dans-la-region-mediter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eumedbridge.eu\/fr\/home-page\/"},{"@type":"ListItem","position":2,"name":"Publications","item":"https:\/\/www.eumedbridge.eu\/publication\/"},{"@type":"ListItem","position":3,"name":"Vers le d\u00e9veloppement d\u2019une plate-forme de connaissances sur l\u2019eau concernant la r\u00e9gion SEMED \u2013 Perspectives de d\u00e9veloppement du secteur de l\u2019eau dans la r\u00e9gion m\u00e9diterran\u00e9enne"}]},{"@type":"WebSite","@id":"https:\/\/www.eumedbridge.eu\/#website","url":"https:\/\/www.eumedbridge.eu\/","name":"EU Medbridge","description":"","publisher":{"@id":"https:\/\/www.eumedbridge.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eumedbridge.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eumedbridge.eu\/#organization","name":"EU Medbridge","url":"https:\/\/www.eumedbridge.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png","contentUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png","width":325,"height":114,"caption":"EU Medbridge"},"image":{"@id":"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eumedbridge\/","https:\/\/x.com\/eumedbridge","https:\/\/www.linkedin.com\/company\/eumedbridge","https:\/\/www.youtube.com\/@eumedbridge","https:\/\/www.instagram.com\/eumedbridge","https:\/\/www.flickr.com\/photos\/euneighbours-south\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication\/212711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication"}],"about":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/types\/publication"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/media\/212607"}],"wp:attachment":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/media?parent=212711"}],"wp:term":[{"taxonomy":"publication_category","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication_category?post=212711"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/country?post=212711"},{"taxonomy":"special_action","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/special_action?post=212711"},{"taxonomy":"custom_tag","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/custom_tag?post=212711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}