{"id":217452,"date":"2023-07-12T16:02:57","date_gmt":"2023-07-12T13:02:57","guid":{"rendered":"https:\/\/eumedbridge.eu\/?post_type=publication&#038;p=217452"},"modified":"2023-07-12T16:02:57","modified_gmt":"2023-07-12T13:02:57","slug":"le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes","status":"publish","type":"publication","link":"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/","title":{"rendered":"Le 6e bulletin d\u2019information du projet INNOMED-UP pr\u00e9sente les activit\u00e9s li\u00e9es \u00e0 l\u2019\u00e9conomie circulaire et aux industries culturelles et cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes"},"content":{"rendered":"<p>Le projet <strong>INNOMED-UP<\/strong> (\u00ab\u00a0Promouvoir le recyclage dans l\u2019\u00e9conomie circulaire par l\u2019innovation et l\u2019\u00e9ducation pour les industries cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes\u00a0\u00bb) touche \u00e0 sa fin. \u00c0 l\u2019\u00e8re des transitions num\u00e9rique et \u00e9cologique, nous avons d\u00e9couvert qu\u2019en ce qui concerne la gestion des d\u00e9chets ces villes sont confront\u00e9es \u00e0 un probl\u00e8me majeur qui exige des solutions directes et efficaces. Par cons\u00e9quent, l\u2019objectif principal de ce programme de recherche innovant \u00e9tait d\u2019\u00e9laborer une strat\u00e9gie de revitalisation pour les villes m\u00e9diterran\u00e9ennes en s\u2019appuyant sur les r\u00e9seaux productifs et cr\u00e9atifs et en les reliant aux pratiques contemporaines et essentielles de l\u2019\u00e9conomie circulaire.<\/p>\n","protected":false},"featured_media":217262,"parent":0,"template":"","publication_category":[],"country":[1956],"special_action":[],"custom_tag":[2312,2315,1884],"class_list":["post-217452","publication","type-publication","status-publish","has-post-thumbnail","hentry","country-region-sud","custom_tag-developpement-durable","custom_tag-emploi-et-entrpreuneuriat","custom_tag-environnement-et-changement-climatique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le 6e bulletin d\u2019information du projet INNOMED-UP pr\u00e9sente les activit\u00e9s li\u00e9es \u00e0 l\u2019\u00e9conomie circulaire et aux industries culturelles et cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes - Voisins de l&#039;UE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le 6e bulletin d\u2019information du projet INNOMED-UP pr\u00e9sente les activit\u00e9s li\u00e9es \u00e0 l\u2019\u00e9conomie circulaire et aux industries culturelles et cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes - Voisins de l&#039;UE\" \/>\n<meta property=\"og:description\" content=\"Le projet INNOMED-UP (\u00ab\u00a0Promouvoir le recyclage dans l\u2019\u00e9conomie circulaire par l\u2019innovation et l\u2019\u00e9ducation pour les industries cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes\u00a0\u00bb) touche \u00e0 sa fin. \u00c0 l\u2019\u00e8re des transitions num\u00e9rique et \u00e9cologique, nous avons d\u00e9couvert qu\u2019en ce qui concerne la gestion des d\u00e9chets ces villes sont confront\u00e9es \u00e0 un probl\u00e8me majeur qui exige des solutions [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/\" \/>\n<meta property=\"og:site_name\" content=\"Voisins de l&#039;UE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eumedbridge\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/07\/Screenshot_20230707_075919_Samsung-Notes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"808\" \/>\n\t<meta property=\"og:image:height\" content=\"1063\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eumedbridge\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/\",\"url\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/\",\"name\":\"Le 6e bulletin d\u2019information du projet INNOMED-UP pr\u00e9sente les activit\u00e9s li\u00e9es \u00e0 l\u2019\u00e9conomie circulaire et aux industries culturelles et cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes - Voisins de l'UE\",\"isPartOf\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/07\/Screenshot_20230707_075919_Samsung-Notes.jpg\",\"datePublished\":\"2023-07-12T13:02:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/#primaryimage\",\"url\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/07\/Screenshot_20230707_075919_Samsung-Notes.jpg\",\"contentUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/07\/Screenshot_20230707_075919_Samsung-Notes.jpg\",\"width\":808,\"height\":1063},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eumedbridge.eu\/fr\/home-page\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publications\",\"item\":\"https:\/\/www.eumedbridge.eu\/publication\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le 6e bulletin d\u2019information du projet INNOMED-UP pr\u00e9sente les activit\u00e9s li\u00e9es \u00e0 l\u2019\u00e9conomie circulaire et aux industries culturelles et cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#website\",\"url\":\"https:\/\/www.eumedbridge.eu\/\",\"name\":\"EU Medbridge\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eumedbridge.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#organization\",\"name\":\"EU Medbridge\",\"url\":\"https:\/\/www.eumedbridge.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png\",\"contentUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png\",\"width\":325,\"height\":114,\"caption\":\"EU Medbridge\"},\"image\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eumedbridge\/\",\"https:\/\/x.com\/eumedbridge\",\"https:\/\/www.linkedin.com\/company\/eumedbridge\",\"https:\/\/www.youtube.com\/@eumedbridge\",\"https:\/\/www.instagram.com\/eumedbridge\",\"https:\/\/www.flickr.com\/photos\/euneighbours-south\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le 6e bulletin d\u2019information du projet INNOMED-UP pr\u00e9sente les activit\u00e9s li\u00e9es \u00e0 l\u2019\u00e9conomie circulaire et aux industries culturelles et cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes - Voisins de l'UE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/","og_locale":"fr_FR","og_type":"article","og_title":"Le 6e bulletin d\u2019information du projet INNOMED-UP pr\u00e9sente les activit\u00e9s li\u00e9es \u00e0 l\u2019\u00e9conomie circulaire et aux industries culturelles et cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes - Voisins de l'UE","og_description":"Le projet INNOMED-UP (\u00ab\u00a0Promouvoir le recyclage dans l\u2019\u00e9conomie circulaire par l\u2019innovation et l\u2019\u00e9ducation pour les industries cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes\u00a0\u00bb) touche \u00e0 sa fin. \u00c0 l\u2019\u00e8re des transitions num\u00e9rique et \u00e9cologique, nous avons d\u00e9couvert qu\u2019en ce qui concerne la gestion des d\u00e9chets ces villes sont confront\u00e9es \u00e0 un probl\u00e8me majeur qui exige des solutions [&hellip;]","og_url":"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/","og_site_name":"Voisins de l'UE","article_publisher":"https:\/\/www.facebook.com\/eumedbridge\/","og_image":[{"width":808,"height":1063,"url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/07\/Screenshot_20230707_075919_Samsung-Notes.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@eumedbridge","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/","url":"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/","name":"Le 6e bulletin d\u2019information du projet INNOMED-UP pr\u00e9sente les activit\u00e9s li\u00e9es \u00e0 l\u2019\u00e9conomie circulaire et aux industries culturelles et cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes - Voisins de l'UE","isPartOf":{"@id":"https:\/\/www.eumedbridge.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/#primaryimage"},"image":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/07\/Screenshot_20230707_075919_Samsung-Notes.jpg","datePublished":"2023-07-12T13:02:57+00:00","breadcrumb":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/#primaryimage","url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/07\/Screenshot_20230707_075919_Samsung-Notes.jpg","contentUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2023\/07\/Screenshot_20230707_075919_Samsung-Notes.jpg","width":808,"height":1063},{"@type":"BreadcrumbList","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/le-6e-bulletin-dinformation-du-projet-innomed-up-presente-les-activites-liees-a-leconomie-circulaire-et-aux-industries-culturelles-et-creatives-dans-les-villes-mediterraneennes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eumedbridge.eu\/fr\/home-page\/"},{"@type":"ListItem","position":2,"name":"Publications","item":"https:\/\/www.eumedbridge.eu\/publication\/"},{"@type":"ListItem","position":3,"name":"Le 6e bulletin d\u2019information du projet INNOMED-UP pr\u00e9sente les activit\u00e9s li\u00e9es \u00e0 l\u2019\u00e9conomie circulaire et aux industries culturelles et cr\u00e9atives dans les villes m\u00e9diterran\u00e9ennes"}]},{"@type":"WebSite","@id":"https:\/\/www.eumedbridge.eu\/#website","url":"https:\/\/www.eumedbridge.eu\/","name":"EU Medbridge","description":"","publisher":{"@id":"https:\/\/www.eumedbridge.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eumedbridge.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eumedbridge.eu\/#organization","name":"EU Medbridge","url":"https:\/\/www.eumedbridge.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png","contentUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png","width":325,"height":114,"caption":"EU Medbridge"},"image":{"@id":"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eumedbridge\/","https:\/\/x.com\/eumedbridge","https:\/\/www.linkedin.com\/company\/eumedbridge","https:\/\/www.youtube.com\/@eumedbridge","https:\/\/www.instagram.com\/eumedbridge","https:\/\/www.flickr.com\/photos\/euneighbours-south\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication\/217452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication"}],"about":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/types\/publication"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/media\/217262"}],"wp:attachment":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/media?parent=217452"}],"wp:term":[{"taxonomy":"publication_category","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication_category?post=217452"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/country?post=217452"},{"taxonomy":"special_action","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/special_action?post=217452"},{"taxonomy":"custom_tag","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/custom_tag?post=217452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}