{"id":234780,"date":"2024-12-06T10:01:05","date_gmt":"2024-12-06T08:01:05","guid":{"rendered":"https:\/\/eumedbridge.eu\/?post_type=publication&#038;p=234780"},"modified":"2024-12-06T10:01:05","modified_gmt":"2024-12-06T08:01:05","slug":"examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie","status":"publish","type":"publication","link":"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/","title":{"rendered":"Examen du plan d\u2019action en faveur des droits de l\u2019homme et de la d\u00e9mocratie"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Le plan d\u2019action de l\u2019UE en faveur des droits de l\u2019homme et de la d\u00e9mocratie pour la p\u00e9riode\u00a02020-2024, qui constitue la troisi\u00e8me it\u00e9ration au titre du cadre strat\u00e9gique de 2012, marque un engagement renouvel\u00e9 vis-\u00e0-vis de la d\u00e9mocratie en tant que question \u00e0 part enti\u00e8re et comprend plusieurs nouveaux domaines prioritaires. Cependant, il ne fournit pas d\u2019orientations claires pour la mise en \u0153uvre de ses objectifs, notamment en ce qui concerne les \u00e9ch\u00e9ances et les responsabilit\u00e9s incombant aux diff\u00e9rents acteurs.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Surtout, le plan d\u2019action n\u2019a pas \u00e9t\u00e9 adapt\u00e9 \u00e0 l\u2019\u00e9volution rapide de la dynamique mondiale, notamment aux conflits de grande ampleur qui remettent en cause les valeurs d\u00e9mocratiques fondamentales de l\u2019UE. La d\u00e9cision de prolonger le plan d\u2019action jusqu\u2019en 2027 de sorte qu\u2019il soit align\u00e9 sur le cadre financier pluriannuel retarde la perspective d\u2019une am\u00e9lioration qualitative majeure du soutien europ\u00e9en \u00e0 la d\u00e9mocratie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ce document d\u2019orientation \u00e9value de mani\u00e8re critique le plan d\u2019action pour la p\u00e9riode\u00a02020-2024 et son examen \u00e0 mi-parcours, en analysant les implications de leur \u00e9laboration et de leur mise en \u0153uvre. Il fournit des informations pour l\u2019\u00e9laboration de futures politiques en mati\u00e8re de d\u00e9mocratie et de droits de l\u2019homme en \u00e9tablissant un lien avec les approches de SHAPEDEM-UE.<\/span><\/p>\n","protected":false},"featured_media":234067,"parent":0,"template":"","publication_category":[],"country":[1956],"special_action":[],"custom_tag":[2313],"class_list":["post-234780","publication","type-publication","status-publish","has-post-thumbnail","hentry","country-region-sud","custom_tag-droit-de-lhomme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Examen du plan d\u2019action en faveur des droits de l\u2019homme et de la d\u00e9mocratie - Voisins de l&#039;UE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Examen du plan d\u2019action en faveur des droits de l\u2019homme et de la d\u00e9mocratie - Voisins de l&#039;UE\" \/>\n<meta property=\"og:description\" content=\"Le plan d\u2019action de l\u2019UE en faveur des droits de l\u2019homme et de la d\u00e9mocratie pour la p\u00e9riode\u00a02020-2024, qui constitue la troisi\u00e8me it\u00e9ration au titre du cadre strat\u00e9gique de 2012, marque un engagement renouvel\u00e9 vis-\u00e0-vis de la d\u00e9mocratie en tant que question \u00e0 part enti\u00e8re et comprend plusieurs nouveaux domaines prioritaires. Cependant, il ne fournit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/\" \/>\n<meta property=\"og:site_name\" content=\"Voisins de l&#039;UE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eumedbridge\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2024\/11\/shapedem.png\" \/>\n\t<meta property=\"og:image:width\" content=\"376\" \/>\n\t<meta property=\"og:image:height\" content=\"519\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eumedbridge\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/\",\"url\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/\",\"name\":\"Examen du plan d\u2019action en faveur des droits de l\u2019homme et de la d\u00e9mocratie - Voisins de l'UE\",\"isPartOf\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2024\/11\/shapedem.png\",\"datePublished\":\"2024-12-06T08:01:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/#primaryimage\",\"url\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2024\/11\/shapedem.png\",\"contentUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2024\/11\/shapedem.png\",\"width\":376,\"height\":519},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eumedbridge.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publications\",\"item\":\"https:\/\/www.eumedbridge.eu\/publication\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Examen du plan d\u2019action en faveur des droits de l\u2019homme et de la d\u00e9mocratie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#website\",\"url\":\"https:\/\/www.eumedbridge.eu\/\",\"name\":\"EU Medbridge\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eumedbridge.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#organization\",\"name\":\"EU Medbridge\",\"url\":\"https:\/\/www.eumedbridge.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png\",\"contentUrl\":\"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png\",\"width\":325,\"height\":114,\"caption\":\"EU Medbridge\"},\"image\":{\"@id\":\"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/eumedbridge\/\",\"https:\/\/x.com\/eumedbridge\",\"https:\/\/www.linkedin.com\/company\/eumedbridge\",\"https:\/\/www.youtube.com\/@eumedbridge\",\"https:\/\/www.instagram.com\/eumedbridge\",\"https:\/\/www.flickr.com\/photos\/euneighbours-south\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Examen du plan d\u2019action en faveur des droits de l\u2019homme et de la d\u00e9mocratie - Voisins de l'UE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/","og_locale":"fr_FR","og_type":"article","og_title":"Examen du plan d\u2019action en faveur des droits de l\u2019homme et de la d\u00e9mocratie - Voisins de l'UE","og_description":"Le plan d\u2019action de l\u2019UE en faveur des droits de l\u2019homme et de la d\u00e9mocratie pour la p\u00e9riode\u00a02020-2024, qui constitue la troisi\u00e8me it\u00e9ration au titre du cadre strat\u00e9gique de 2012, marque un engagement renouvel\u00e9 vis-\u00e0-vis de la d\u00e9mocratie en tant que question \u00e0 part enti\u00e8re et comprend plusieurs nouveaux domaines prioritaires. Cependant, il ne fournit [&hellip;]","og_url":"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/","og_site_name":"Voisins de l'UE","article_publisher":"https:\/\/www.facebook.com\/eumedbridge\/","og_image":[{"width":376,"height":519,"url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2024\/11\/shapedem.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@eumedbridge","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/","url":"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/","name":"Examen du plan d\u2019action en faveur des droits de l\u2019homme et de la d\u00e9mocratie - Voisins de l'UE","isPartOf":{"@id":"https:\/\/www.eumedbridge.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/#primaryimage"},"image":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2024\/11\/shapedem.png","datePublished":"2024-12-06T08:01:05+00:00","breadcrumb":{"@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/#primaryimage","url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2024\/11\/shapedem.png","contentUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2024\/11\/shapedem.png","width":376,"height":519},{"@type":"BreadcrumbList","@id":"https:\/\/www.eumedbridge.eu\/fr\/publication\/examen-du-plan-daction-en-faveur-des-droits-de-lhomme-et-de-la-democratie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eumedbridge.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Publications","item":"https:\/\/www.eumedbridge.eu\/publication\/"},{"@type":"ListItem","position":3,"name":"Examen du plan d\u2019action en faveur des droits de l\u2019homme et de la d\u00e9mocratie"}]},{"@type":"WebSite","@id":"https:\/\/www.eumedbridge.eu\/#website","url":"https:\/\/www.eumedbridge.eu\/","name":"EU Medbridge","description":"","publisher":{"@id":"https:\/\/www.eumedbridge.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eumedbridge.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eumedbridge.eu\/#organization","name":"EU Medbridge","url":"https:\/\/www.eumedbridge.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png","contentUrl":"https:\/\/www.eumedbridge.eu\/wp-content\/uploads\/2021\/12\/Logo.png","width":325,"height":114,"caption":"EU Medbridge"},"image":{"@id":"https:\/\/www.eumedbridge.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eumedbridge\/","https:\/\/x.com\/eumedbridge","https:\/\/www.linkedin.com\/company\/eumedbridge","https:\/\/www.youtube.com\/@eumedbridge","https:\/\/www.instagram.com\/eumedbridge","https:\/\/www.flickr.com\/photos\/euneighbours-south\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication\/234780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication"}],"about":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/types\/publication"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/media\/234067"}],"wp:attachment":[{"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/media?parent=234780"}],"wp:term":[{"taxonomy":"publication_category","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/publication_category?post=234780"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/country?post=234780"},{"taxonomy":"special_action","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/special_action?post=234780"},{"taxonomy":"custom_tag","embeddable":true,"href":"https:\/\/www.eumedbridge.eu\/fr\/wp-json\/wp\/v2\/custom_tag?post=234780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}